{"id":2365,"date":"2022-09-15T13:17:02","date_gmt":"2022-09-15T11:17:02","guid":{"rendered":"https:\/\/institucional.us.es\/aaaetsi\/?p=2365"},"modified":"2022-09-15T13:17:02","modified_gmt":"2022-09-15T11:17:02","slug":"bailes-de-salon-2022-2023","status":"publish","type":"post","link":"https:\/\/institucional.us.es\/aaaetsi\/2022\/09\/15\/bailes-de-salon-2022-2023\/","title":{"rendered":"Bailes de Sal\u00f3n 2022-2023"},"content":{"rendered":"\n<p>Despu\u00e9s de disfrutar del verano, vamos a comenzar&nbsp;<strong>el octavo a\u00f1o de las clases de Baile de Sal\u00f3n.<\/strong><\/p>\n\n\n\n<p>Seguiremos contando con Paco Gallardo,&nbsp; bailar\u00edn y profesor con 20 a\u00f1os de experiencia en la docencia de bailes Latinos y de Sal\u00f3n y titulado por la AEPBS (Asoc. Espa\u00f1ola de Profesores de Bailes de Sal\u00f3n).<\/p>\n\n\n\n<p>Las clases se impartir\u00e1n los lunes, a partir del&nbsp;<strong>3 de octubre<\/strong>&nbsp;en el local de la \u201c<strong>Asociaci\u00f3n de Vecinos Las Ciencias<\/strong>&nbsp;(c\/ Flor de Gitanilla 2), en dos grupos el primero de principiantes&nbsp;entre las 19:00 y 20:00h&nbsp;y el segundo de veteranos&nbsp;entre las 20:00 y 21:00h, siendo necesarias 6 parejas para formar un grupo.&nbsp;&nbsp;<\/p>\n\n\n\n<p>El local, que ya disfrutamos el curso pasado, cuenta con unas condiciones \u00f3ptimas para practicar los bailes de sal\u00f3n y el aforo m\u00e1ximo por grupo ser\u00e1 de 8 parejas.&nbsp;<\/p>\n\n\n\n<p>Es necesario asistir con pareja, siendo el precio por persona de 30\u20ac\/mes (4 clases)<\/p>\n\n\n\n<p>Si est\u00e1s interesado, env\u00eda un correo o llama a la&nbsp;Asociaci\u00f3n especificando tus datos y los de tu acompa\u00f1ante antes del&nbsp;29 de septiembre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de disfrutar del verano, vamos a comenzar&nbsp;el octavo a\u00f1o de las clases de Baile de Sal\u00f3n. Seguiremos contando con Paco Gallardo,&nbsp; bailar\u00edn y profesor con 20 a\u00f1os de experiencia en la docencia de bailes Latinos y de Sal\u00f3n y titulado por la AEPBS (Asoc. Espa\u00f1ola de Profesores de Bailes de Sal\u00f3n). Las clases se [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-2365","post","type-post","status-publish","format-standard","hentry","category-actividades"],"acf":[],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/institucional.us.es\/aaaetsi\/wp-json\/wp\/v2\/posts\/2365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/institucional.us.es\/aaaetsi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/institucional.us.es\/aaaetsi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/institucional.us.es\/aaaetsi\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/institucional.us.es\/aaaetsi\/wp-json\/wp\/v2\/comments?post=2365"}],"version-history":[{"count":1,"href":"https:\/\/institucional.us.es\/aaaetsi\/wp-json\/wp\/v2\/posts\/2365\/revisions"}],"predecessor-version":[{"id":2366,"href":"https:\/\/institucional.us.es\/aaaetsi\/wp-json\/wp\/v2\/posts\/2365\/revisions\/2366"}],"wp:attachment":[{"href":"https:\/\/institucional.us.es\/aaaetsi\/wp-json\/wp\/v2\/media?parent=2365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/institucional.us.es\/aaaetsi\/wp-json\/wp\/v2\/categories?post=2365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/institucional.us.es\/aaaetsi\/wp-json\/wp\/v2\/tags?post=2365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}