{"id":2805,"date":"2023-03-02T11:03:52","date_gmt":"2023-03-02T10:03:52","guid":{"rendered":"https:\/\/institucional.us.es\/aaaetsi\/?p=2805"},"modified":"2023-03-02T11:03:52","modified_gmt":"2023-03-02T10:03:52","slug":"oferta-empleo-disace-energia","status":"publish","type":"post","link":"https:\/\/institucional.us.es\/aaaetsi\/2023\/03\/02\/oferta-empleo-disace-energia\/","title":{"rendered":"OFERTA EMPLEO DISACE ENERG\u00cdA"},"content":{"rendered":"\n<p>La empresa&nbsp;Disace Energ\u00eda S.L., se ha puesto en contacto con la Asociaci\u00f3n porque est\u00e1n&nbsp;interesados en incorporar a un ingeniero el\u00e9ctrico con perfil comercial a su equipo. Estos son los datos de la oferta:<\/p>\n\n\n\n<p>Datos de la empresa:<\/p>\n\n\n\n<p>Nombre:&nbsp;Disace Energ\u00eda S.L.<\/p>\n\n\n\n<p>Direcci\u00f3n postal completa:&nbsp;P.I. Fuentequintillo (Montequinto). C\/ V\u00eda Salaria, 4. 41089 Dos Hermanas (Sevilla).<\/p>\n\n\n\n<p>Enviar C.V. a:&nbsp;<\/p>\n\n\n\n<p>Pablo Bernal<\/p>\n\n\n\n<p>Email:&nbsp;pablo@disace-energia.com<\/p>\n\n\n\n<p>Datos de la oferta de empleo:<\/p>\n\n\n\n<p>Puesto requerido: T\u00e9cnico comercial<\/p>\n\n\n\n<p>Descripci\u00f3n del puesto: Departamento Comercial. Empresa especialista en distribuci\u00f3n de material el\u00e9ctrico de media y alta tensi\u00f3n busca ingeniero\/a el\u00e9ctrico para desempe\u00f1ar labores tipo del departamento de ventas. Debe residir preferiblemente en Sevilla o alrededores.<\/p>\n\n\n\n<p>Ubicaci\u00f3n: Andaluc\u00eda Occidental.<\/p>\n\n\n\n<p>N\u00aa vacantes: 1<\/p>\n\n\n\n<p>Tipo de contrato: Indefinido. Jornada Completa.<\/p>\n\n\n\n<p>Horario: lunes a jueves: 8 a 14h y 16 a 19h. viernes: 8 a 15h.<\/p>\n\n\n\n<p>Salario: A concretar. Incluye veh\u00edculo de empresa.<\/p>\n\n\n\n<p>Estudios requeridos: Ingenier\u00eda El\u00e9ctrica \/ Ingenier\u00eda Industrial (especialidad electricidad).<\/p>\n\n\n\n<p>Experiencia necesaria: Valorable, aunque no requerida.<\/p>\n\n\n\n<p>Conocimientos deseados: Ingenier\u00eda El\u00e9ctrica.<\/p>\n\n\n\n<p>Requisitos del puesto: Disponibilidad para viajar, carnet de conducir B, importante tener dotes comerciales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La empresa&nbsp;Disace Energ\u00eda S.L., se ha puesto en contacto con la Asociaci\u00f3n porque est\u00e1n&nbsp;interesados en incorporar a un ingeniero el\u00e9ctrico con perfil comercial a su equipo. Estos son los datos de la oferta: Datos de la empresa: Nombre:&nbsp;Disace Energ\u00eda S.L. Direcci\u00f3n postal completa:&nbsp;P.I. Fuentequintillo (Montequinto). C\/ V\u00eda Salaria, 4. 41089 Dos Hermanas (Sevilla). Enviar C.V. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-2805","post","type-post","status-publish","format-standard","hentry","category-empleo"],"acf":[],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/institucional.us.es\/aaaetsi\/wp-json\/wp\/v2\/posts\/2805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/institucional.us.es\/aaaetsi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/institucional.us.es\/aaaetsi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/institucional.us.es\/aaaetsi\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/institucional.us.es\/aaaetsi\/wp-json\/wp\/v2\/comments?post=2805"}],"version-history":[{"count":1,"href":"https:\/\/institucional.us.es\/aaaetsi\/wp-json\/wp\/v2\/posts\/2805\/revisions"}],"predecessor-version":[{"id":2806,"href":"https:\/\/institucional.us.es\/aaaetsi\/wp-json\/wp\/v2\/posts\/2805\/revisions\/2806"}],"wp:attachment":[{"href":"https:\/\/institucional.us.es\/aaaetsi\/wp-json\/wp\/v2\/media?parent=2805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/institucional.us.es\/aaaetsi\/wp-json\/wp\/v2\/categories?post=2805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/institucional.us.es\/aaaetsi\/wp-json\/wp\/v2\/tags?post=2805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}